{"id":15599,"date":"2026-06-03T12:23:30","date_gmt":"2026-06-03T17:23:30","guid":{"rendered":"https:\/\/neuroeconomix.com\/?p=15599"},"modified":"2026-06-01T13:24:02","modified_gmt":"2026-06-01T18:24:02","slug":"por-que-fracasan-las-intervenciones-de-las-eps","status":"publish","type":"post","link":"https:\/\/neuroeconomix.com\/es\/por-que-fracasan-las-intervenciones-de-las-eps\/","title":{"rendered":"\u00bfPor qu\u00e9 fracasan las intervenciones de las EPS?"},"content":{"rendered":"\n<p class=\"has-text-align-center wp-block-paragraph\"><\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p class=\"has-text-align-left wp-block-paragraph\">La Contralor\u00eda General de la Rep\u00fablica (CGR) public\u00f3 un informe[1] sobre los resultados de las intervenciones a las EPS ordenadas por la Superintendencia Nacional de Salud entre los a\u00f1os 2019 a 2024<\/p>\n<\/blockquote>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La CGR encontr\u00f3 que los indicadores de base que se consideraron como justificaci\u00f3n de las intervenciones se han deteriorado, especialmente los financieros.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Complementariamente se hallaron datos alarmantes como el significativo incremento de las quejas y tutelas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">M\u00e1s all\u00e1 del informe mencionado, en este blog se ha realizado un an\u00e1lisis de las razones principales que han provocado que ese tipo de intervenciones fracasen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>La norma aplicable<\/strong><strong><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En primera instancia debemos considerar que el r\u00e9gimen de insolvencia del sector salud es el establecido en el Estatuto Org\u00e1nico del Sistema Financiero (EOSF). Por consiguiente, cualquier intervenci\u00f3n o liquidaci\u00f3n se realiza de conformidad con lo establecido en dicho estatuto.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El EOSF se dise\u00f1\u00f3 para proteger los ahorros de los clientes de las entidades financieras, es decir, que no es precisamente la norma apropiada para garantizar la prestaci\u00f3n de servicios en el sistema de salud.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Adicionalmente, el procedimiento establecido en el EOSF hace pr\u00e1cticamente imposible llegar a un acuerdo con acreedores, por lo que la \u00fanica opci\u00f3n es recurrir a la capitalizaci\u00f3n que en el caso de las EPS es muy dif\u00edcil. Al no ser posible la capitalizaci\u00f3n, estas entidades terminan en un proceso de liquidaci\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sobre la aplicaci\u00f3n del EOSF a los procesos de insolvencia del sector salud, en el informe de la CGR antes mencionado se encuentra la siguiente observaci\u00f3n:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>\u201cAdicionalmente, la remisi\u00f3n al Estatuto Org\u00e1nico del Sistema Financiero para las intervenciones, dise\u00f1ado para entidades bancarias y no de aseguramiento en salud, genera tensiones conceptuales entre l\u00f3gica de rentabilidad financiera y l\u00f3gica de derecho fundamental, lo cual es susceptible de revisi\u00f3n por parte de las autoridades que lideran el SGSSS\u201d.<strong>[2]<\/strong>\u00a0 <\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>La vulneraci\u00f3n del debido proceso. <\/strong><strong><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Mediante el Auto 007 de 2025, la Corte Constitucional orden\u00f3 al gobierno realizar ajustes de la unidad de pago por capitaci\u00f3n (UPC), sin que, hasta la fecha, el gobierno haya cumplido con dicho mandato.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Una vez la comisi\u00f3n S\u00e9ptima del senado archiv\u00f3 la reforma a la salud presentada por el gobierno, la Superintendencia Nacional de Salud orden\u00f3 las intervenciones de la Nueva EPS, Sanitas EPS y Servicio Occidental de Salud EPS (SOS EPS).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Con relaci\u00f3n a la intervenci\u00f3n de Sanitas EPS, la Corte Constitucional en la sentencia SU-227 de 2025 dej\u00f3 sin efectos la resoluci\u00f3n por la cual fue ordenada, considerando lo siguiente:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>\u201cPor las razones expuestas se concluye que la Superintendencia Nacional de Salud al expedir la Resoluci\u00f3n No. 2024160000003002-6 del 2 de abril de 2024 y la Resoluci\u00f3n 2024100000003060-6 del 10 de abril de 2024, que la corrigi\u00f3, incurri\u00f3 en una arbitrariedad que desconoci\u00f3 los mandatos constitucionales en cuanto al seguimiento y cumplimiento de \u00f3rdenes emitidas por la Corte Constitucional para el goce efectivo del derecho a la salud, bajo los cuales deb\u00eda regir su conducta y, en consecuencia, vulner\u00f3 de manera grave, el derecho al debido proceso de los accionantes y de la EPS Sanitas.\u201d<\/em><em><\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Para la Corte Constitucional el desacato del gobierno a las \u00f3rdenes dadas en el mencionado auto implica que se incurri\u00f3 en la violaci\u00f3n al debido proceso y por esa raz\u00f3n dictamin\u00f3 que Sanitas EPS fuera devuelta a sus due\u00f1os.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En otras palabras, el gobierno intervino una entidad por inconvenientes que el mismo gener\u00f3 y no tuvo en cuenta los efectos de sus decisiones en la situaci\u00f3n financiera de la EPS mencionada por no acatar la orden de la Corte Constitucional de incrementar la UPC.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Teniendo en cuenta que es una sentencia unificada, es decir que es de obligatorio cumplimiento para los jueces que resuelvan casos similares, mediante otra acci\u00f3n de tutela el Tribunal Administrativo de Antioquia orden\u00f3 la devoluci\u00f3n a sus propietarios de Saviasalud EPS.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>La insuficiencia de la UPC<\/strong><strong><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Como complemento de lo anterior, debemos considerar que la Corte Constitucional en el mismo auto antes citado, expedido dentro del proceso de seguimiento a la sentencia T-780 de 2008, orden\u00f3 que la UPC fuera actualizada.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sin embargo, el gobierno nacional no acat\u00f3 dicha orden. Al contrario, \u00fanicamente aument\u00f3 la UPC en el mismo valor de la inflaci\u00f3n en el a\u00f1o 2025 y significativamente por debajo del incremento del salario m\u00ednimo. Para 2026, la UPC fue incrementada por encima de la inflaci\u00f3n pero significativamente por debajo del aumento del salario m\u00ednimo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Adicionalmente, las mesas de trabajo que se convocaron para cumplir con la orden del Alto Tribunal no llegaron a ninguna conclusi\u00f3n que permitiera un an\u00e1lisis t\u00e9cnico sobre el ajuste que requiere la UPC.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En reiteradas ocasiones y diferentes entidades realizaron estudios que demostraron la insuficiencia de la UPC. Inclusive, interventores de EPS manifestaron p\u00fablicamente que la UPC era insuficiente.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>La idoneidad y el cambio permanente de los interventores<\/strong><strong><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Las personas designadas como interventores de las EPS no contaban con la suficiente experiencia y conocimiento sobre la administraci\u00f3n del aseguramiento.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Como consecuencia de lo anterior, hubo cambios permanentes de interventores que no permitieron un proceso gerencial continuo en dichas entidades, ni la ejecuci\u00f3n de estrategias a largo plazo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Tales inconvenientes generaron a su vez desconfianza e incertidumbre en el sector.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Las consecuencias son las esperadas\u2026<\/strong><strong><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Aunque el informe de la CGR abarca un corto periodo de tiempo de la historia de las intervenciones de las EPS, no se puede desconocer que todas o gran parte de las razones que han sido expuestas en este blog como causantes del fracaso de las intervenciones, son comunes a todas las medidas de este tipo que se han tomado durante los a\u00f1os de vigencia del SGSSS.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">No obstante, debe considerarse de manera principal y determinante que el r\u00e9gimen de insolvencia para las entidades del sector salud, o sea el establecido en el EOSF, no resulta adecuado para garantizar la prestaci\u00f3n de un servicio que involucra un derecho fundamental.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Es incuestionable que el sistema de salud ha venido sufriendo un deterioro gradual desde mucho antes del periodo considerado en el informe de la CGR, sin embargo, tampoco es menos cierto que las intervenciones en ning\u00fan caso han servido para resolver o mejorar la situaci\u00f3n financiera de las EPS y han conllevado al consecuente deterioro de la prestaci\u00f3n de los servicios de salud.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Las razones expuestas conducen a que las intervenciones terminen en liquidaci\u00f3n o en un agravamiento de las condiciones de las EPS tal como se hace manifiesto en el informe de la CGR.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En conclusi\u00f3n, mientras que para el sector salud no se modifique la norma aplicable para los procesos de insolvencia, el gobierno persista en su desacato a las \u00f3rdenes de la Corte Constitucional para actualizar la UPC y contin\u00faen designando a personas no id\u00f3neas, los resultados ser\u00e1n los previsibles e irremediablemente las intervenciones que se hagan de EPS muy posiblemente terminar\u00e1n en liquidaci\u00f3n con el correspondiente perjuicio en la prestaci\u00f3n del servicio.<\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-theme-palette-1-color\">Referencias:<\/mark><\/strong><\/p>\n\n\n\n<ol class=\"wp-block-list\">\n<li>El informe completo se puede consultar en la p\u00e1gina web: <a href=\"https:\/\/www.contraloria.gov.co\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/www.contraloria.gov.co<\/a><br><\/li>\n\n\n\n<li>SGSSS: sistema general de seguridad social en salud, de conformidad con las definiciones que se encuentran en la p\u00e1gina 8 del informe.<\/li>\n<\/ol>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n","protected":false},"excerpt":{"rendered":"<p>La Contralor\u00eda General de la Rep\u00fablica (CGR) public\u00f3 un informe  sobre los resultados de las intervenciones a las EPS ordenadas por la Superintendencia Nacional de Salud entre los a\u00f1os 2019 a 2024<\/p>\n","protected":false},"author":9,"featured_media":15600,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"_kad_blocks_custom_css":"","_kad_blocks_head_custom_js":"","_kad_blocks_body_custom_js":"","_kad_blocks_footer_custom_js":"","_kadence_starter_templates_imported_post":false,"_kad_post_transparent":"","_kad_post_title":"","_kad_post_layout":"","_kad_post_sidebar_id":"","_kad_post_content_style":"","_kad_post_vertical_padding":"","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"_kad_post_classname":"","footnotes":""},"categories":[4,8],"tags":[878,165,726,876,877,692,97,437,53,106,687,727,767,556,125,674,59,474,186],"ppma_author":[743],"class_list":["post-15599","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog","category-sistema-de-salud","tag-auto-007-de-2025","tag-blog","tag-blog-salud","tag-cgr","tag-contraloria-general-de-la-republica","tag-eosf","tag-eps","tag-industria-farmaceutica","tag-medicamentos","tag-minsalud","tag-msps","tag-noticias-salud","tag-profesionales-de-salud","tag-salud-colombia","tag-salud-publica","tag-sector-farmaceutico","tag-sistema-de-salud","tag-superintendencia-nacional-de-salud","tag-upc"],"taxonomy_info":{"category":[{"value":4,"label":"Blogs Publicados"},{"value":8,"label":"Sistema de Salud"}],"post_tag":[{"value":878,"label":"Auto 007 de 2025"},{"value":165,"label":"blog"},{"value":726,"label":"blog salud"},{"value":876,"label":"CGR"},{"value":877,"label":"contralor\u00eda general de la rep\u00fablica"},{"value":692,"label":"EOSF"},{"value":97,"label":"EPS"},{"value":437,"label":"industria farmac\u00e9utica"},{"value":53,"label":"medicamentos"},{"value":106,"label":"MINSALUD"},{"value":687,"label":"MSPS"},{"value":727,"label":"noticias salud"},{"value":767,"label":"profesionales de salud"},{"value":556,"label":"salud Colombia"},{"value":125,"label":"salud p\u00fablica"},{"value":674,"label":"sector farmac\u00e9utico"},{"value":59,"label":"sistema de salud"},{"value":474,"label":"Superintendencia Nacional de Salud"},{"value":186,"label":"UPC"}]},"featured_image_src_large":["https:\/\/neuroeconomix.com\/wp-content\/uploads\/2026\/06\/Portada-Blog-IntervencionesEPS.png",640,427,false],"author_info":{"display_name":"Francisco Jos\u00e9 Garc\u00eda Lara","author_link":"https:\/\/neuroeconomix.com\/es\/author\/fgarcia\/"},"comment_info":0,"category_info":[{"term_id":4,"name":"Blogs Publicados","slug":"blog","term_group":0,"term_taxonomy_id":4,"taxonomy":"category","description":"","parent":0,"count":266,"filter":"raw","cat_ID":4,"category_count":266,"category_description":"","cat_name":"Blogs Publicados","category_nicename":"blog","category_parent":0},{"term_id":8,"name":"Sistema de Salud","slug":"sistema-de-salud","term_group":0,"term_taxonomy_id":8,"taxonomy":"category","description":"","parent":0,"count":169,"filter":"raw","cat_ID":8,"category_count":169,"category_description":"","cat_name":"Sistema de Salud","category_nicename":"sistema-de-salud","category_parent":0}],"tag_info":[{"term_id":878,"name":"Auto 007 de 2025","slug":"auto-007-de-2025","term_group":0,"term_taxonomy_id":878,"taxonomy":"post_tag","description":"","parent":0,"count":1,"filter":"raw"},{"term_id":165,"name":"blog","slug":"blog","term_group":0,"term_taxonomy_id":165,"taxonomy":"post_tag","description":"","parent":0,"count":29,"filter":"raw"},{"term_id":726,"name":"blog salud","slug":"blog-salud","term_group":0,"term_taxonomy_id":726,"taxonomy":"post_tag","description":"","parent":0,"count":29,"filter":"raw"},{"term_id":876,"name":"CGR","slug":"cgr","term_group":0,"term_taxonomy_id":876,"taxonomy":"post_tag","description":"","parent":0,"count":2,"filter":"raw"},{"term_id":877,"name":"contralor\u00eda general de la rep\u00fablica","slug":"contraloria-general-de-la-republica","term_group":0,"term_taxonomy_id":877,"taxonomy":"post_tag","description":"","parent":0,"count":1,"filter":"raw"},{"term_id":692,"name":"EOSF","slug":"eosf","term_group":0,"term_taxonomy_id":692,"taxonomy":"post_tag","description":"","parent":0,"count":2,"filter":"raw"},{"term_id":97,"name":"EPS","slug":"eps","term_group":0,"term_taxonomy_id":97,"taxonomy":"post_tag","description":"","parent":0,"count":50,"filter":"raw"},{"term_id":437,"name":"industria farmac\u00e9utica","slug":"industria-farmaceutica","term_group":0,"term_taxonomy_id":437,"taxonomy":"post_tag","description":"","parent":0,"count":61,"filter":"raw"},{"term_id":53,"name":"medicamentos","slug":"medicamentos","term_group":0,"term_taxonomy_id":53,"taxonomy":"post_tag","description":"","parent":0,"count":73,"filter":"raw"},{"term_id":106,"name":"MINSALUD","slug":"minsalud","term_group":0,"term_taxonomy_id":106,"taxonomy":"post_tag","description":"","parent":0,"count":67,"filter":"raw"},{"term_id":687,"name":"MSPS","slug":"msps","term_group":0,"term_taxonomy_id":687,"taxonomy":"post_tag","description":"","parent":0,"count":19,"filter":"raw"},{"term_id":727,"name":"noticias salud","slug":"noticias-salud","term_group":0,"term_taxonomy_id":727,"taxonomy":"post_tag","description":"","parent":0,"count":27,"filter":"raw"},{"term_id":767,"name":"profesionales de salud","slug":"profesionales-de-salud","term_group":0,"term_taxonomy_id":767,"taxonomy":"post_tag","description":"","parent":0,"count":9,"filter":"raw"},{"term_id":556,"name":"salud Colombia","slug":"salud-colombia","term_group":0,"term_taxonomy_id":556,"taxonomy":"post_tag","description":"","parent":0,"count":41,"filter":"raw"},{"term_id":125,"name":"salud p\u00fablica","slug":"salud-publica","term_group":0,"term_taxonomy_id":125,"taxonomy":"post_tag","description":"","parent":0,"count":64,"filter":"raw"},{"term_id":674,"name":"sector farmac\u00e9utico","slug":"sector-farmaceutico","term_group":0,"term_taxonomy_id":674,"taxonomy":"post_tag","description":"","parent":0,"count":34,"filter":"raw"},{"term_id":59,"name":"sistema de salud","slug":"sistema-de-salud","term_group":0,"term_taxonomy_id":59,"taxonomy":"post_tag","description":"","parent":0,"count":99,"filter":"raw"},{"term_id":474,"name":"Superintendencia Nacional de Salud","slug":"superintendencia-nacional-de-salud","term_group":0,"term_taxonomy_id":474,"taxonomy":"post_tag","description":"","parent":0,"count":11,"filter":"raw"},{"term_id":186,"name":"UPC","slug":"upc","term_group":0,"term_taxonomy_id":186,"taxonomy":"post_tag","description":"","parent":0,"count":30,"filter":"raw"}],"authors":[{"term_id":743,"user_id":9,"is_guest":0,"slug":"fgarcia","display_name":"Francisco Jos\u00e9 Garc\u00eda Lara","avatar_url":"https:\/\/neuroeconomix.com\/wp-content\/uploads\/2025\/02\/profiole-neuro007-150x150.png","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/neuroeconomix.com\/es\/wp-json\/wp\/v2\/posts\/15599","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/neuroeconomix.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/neuroeconomix.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/neuroeconomix.com\/es\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/neuroeconomix.com\/es\/wp-json\/wp\/v2\/comments?post=15599"}],"version-history":[{"count":1,"href":"https:\/\/neuroeconomix.com\/es\/wp-json\/wp\/v2\/posts\/15599\/revisions"}],"predecessor-version":[{"id":15601,"href":"https:\/\/neuroeconomix.com\/es\/wp-json\/wp\/v2\/posts\/15599\/revisions\/15601"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/neuroeconomix.com\/es\/wp-json\/wp\/v2\/media\/15600"}],"wp:attachment":[{"href":"https:\/\/neuroeconomix.com\/es\/wp-json\/wp\/v2\/media?parent=15599"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/neuroeconomix.com\/es\/wp-json\/wp\/v2\/categories?post=15599"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/neuroeconomix.com\/es\/wp-json\/wp\/v2\/tags?post=15599"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/neuroeconomix.com\/es\/wp-json\/wp\/v2\/ppma_author?post=15599"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}